{"id":16135,"date":"2021-06-28T09:04:43","date_gmt":"2021-06-28T13:04:43","guid":{"rendered":"https:\/\/jimbovard.com\/blog\/?p=16135"},"modified":"2021-06-28T15:18:11","modified_gmt":"2021-06-28T19:18:11","slug":"french-translations-of-conspiracy-theory-and-extremism-articles","status":"publish","type":"post","link":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/","title":{"rendered":"French Translations of Conspiracy Theory and Extremism Articles"},"content":{"rendered":"<p>Here are a couple recent articles translated into French. The &#8220;conspiracy theory&#8221; article was first published by the <a href=\"https:\/\/www.theamericanconservative.com\/articles\/the-conspiracy-theory-charade\/\">American Conservative<\/a> and reposted by Zero Hedge.\u00a0 The second article, on Extremism, was first published by the <a href=\"https:\/\/www.fff.org\/explore-freedom\/article\/extremism-as-a-ticket-to-tyrannize\/\">Future of Freedom Foundation<\/a> and republished by Consortium News.<\/p>\n<h1 class=\"post-title entry-title fittexted_for_single_post_title\"><a href=\"https:\/\/www.aubedigitale.com\/la-comedie-de-la-theorie-du-complot\/?__cf_chl_captcha_tk__=ea559008faee593c94087b050481e6d30ec3ad0f-1624884930-0-ASEMnO9lC-ccJ_aIXcDZzhbsM0Ag5_UN0U9_DnTDhz_8OWYhMosV15jqrxWorXlG3YzfyKpR4cvQDEDgSPlgx-LTilXOj3EUKBXny9kuxTllCAVlLhxiV56fZK3fV91w35Ms__gwBUOFOQ3IBKAr7fxV4WfWspp8aqjqoLEY3n0EsHqwqf5E28qYiqTqAt0H39AygZeF4tx3yhOFNweFBBxbYzTWfHxiV8LOKzkqHs4OasS4JMJW9jWa3icuMiI-WVrIzmTbKZLr_hRGfzq6d-4X4HV8MImtdTSM4rQiZlUJXplQM_6CNYGOb1XYD6EgJweXj02LHWdJE2vXN1IcBgkHHZW2Ys0HU9uW-g9RsHsvq4Hx0Si6hm2L7uDbFdLm9pHiSvK0B3LsiLqVxWmZKlOAK_-7M1hpqU21Nh_bA_U1fdVkh_Y_hLL5pXjPrXp3qaFAv_6TASJwrHo3P8BMS1YrxmXQEURHWwvVsYPAwINaPx2leM2sYo7RPMwuP3vNfdaNZo5hFczNyRe7ADUyio3IJUVsyPGPWrtAZl_AeEGf3IljY4AhZkvDpNV7zo0Qokm1rfoWfckVGQHogex_gP8x9gIIYajKrLVE7OuXkZhYfnEpxE8YgAe6tQm9kz89jxgax0Pnhssxu7x9nGMngegiISjaEqBhoAh-PUc0OdPMmGUDF9ZkLi_BmhmQ-atAC1GIH6naQ52vnTGP9oy5T0E\">La com\u00e9die de la \u00ab\u00a0th\u00e9orie du complot<\/a>\u00a0\u00bb<\/h1>\n<p class=\"post-byline\">par \u00a0 <span class=\"vcard author\">James Bovard<\/span> \u00b7 Publi\u00e9 <time class=\"published\" datetime=\"2021-06-25T19:45:53+02:00\">25 juin 2021<\/time> \u00b7 Mis \u00e0 jour <time class=\"updated\" datetime=\"2021-06-25T09:00:28+02:00\">25 juin 2021<\/time><\/p>\n<div class=\"entry themeform fittexted_for_entry\">\n<div class=\"entry-inner\">\n<p><strong>Comment le gouvernement et les m\u00e9dias utilisent cette formule pour se d\u00e9barrasser de l\u2019opposition\u2026<\/strong><\/p>\n<p>Le rapport de Biden sur la <a href=\"https:\/\/www.whitehouse.gov\/wp-content\/uploads\/2021\/06\/National-Strategy-for-Countering-Domestic-Terrorism.pdf\" target=\"_blank\" rel=\"noopener\">\u00ab\u00a0Strat\u00e9gie nationale de lutte contre le terrorisme int\u00e9rieur\u00a0\u00bb<\/a>, publi\u00e9 la semaine derni\u00e8re, d\u00e9clare que pour \u00ab\u00a0renforcer la foi dans la d\u00e9mocratie am\u00e9ricaine\u00a0\u00bb, il faut \u00ab\u00a0trouver des moyens de contrer l\u2019influence et l\u2019impact des dangereuses th\u00e9ories du complot\u00a0\u00bb. <strong>Au cours des derni\u00e8res d\u00e9cennies, les th\u00e9ories du complot se sont multipli\u00e9es presque aussi vite que les mensonges et les dissimulations des gouvernements<\/strong>. Bien que de nombreuses all\u00e9gations soient ridiculement farfelues, l\u2019establishment politique et les m\u00e9dias apposent syst\u00e9matiquement l\u2019\u00e9tiquette \u00ab\u00a0th\u00e9orie du complot\u00a0\u00bb \u00e0 toute remise en cause de leur domination.<\/p>\n<div class=\"code-block code-block-4\"><\/div>\n<p><strong>Selon <a href=\"https:\/\/poseidon01.ssrn.com\/delivery.php?ID=823120105064101065001102108078017109052085065093048051024026075074117101066097006028020016099038123036046072009090064094077094025090034086038096116080094004089015054089003003103104123027069086119106011116077120119097127083089072021122088122120093064&amp;EXT=pdf&amp;INDEX=TRUE\" target=\"_blank\" rel=\"noopener\">Cass Sunstein<\/a>, professeur de droit \u00e0 Harvard et tsar de la r\u00e9glementation d\u2019Obama, une th\u00e9orie du complot est \u00ab\u00a0un effort pour expliquer un \u00e9v\u00e9nement ou une pratique en faisant r\u00e9f\u00e9rence aux machinations de personnes puissantes, qui ont \u00e9galement r\u00e9ussi \u00e0 dissimuler leur r\u00f4le\u00a0\u00bb.<\/strong> Les citoyens raisonnables sont cens\u00e9s pr\u00e9sumer que le gouvernement cr\u00e9e des milliers de milliards de pages de nouveaux secrets chaque ann\u00e9e pour leur propre bien, et non pour cacher quoi que ce soit au public.<\/p>\n<p><strong>Au d\u00e9but des ann\u00e9es 1960, les th\u00e9ories du complot \u00e9taient pratiquement un non-sujet, car 75 % des Am\u00e9ricains faisaient confiance au gouvernement f\u00e9d\u00e9ral.<\/strong> Une telle cr\u00e9dulit\u00e9 n\u2019a pas surv\u00e9cu \u00e0 l\u2019assassinat de John F. Kennedy. Sept jours apr\u00e8s que Kennedy a \u00e9t\u00e9 abattu le 22 novembre 1963, le pr\u00e9sident Lyndon Johnson a cr\u00e9\u00e9 une commission (connue plus tard sous le nom de Commission Warren) pour supprimer la controverse sur l\u2019assassinat. Johnson et le chef du FBI, J. Edgar Hoover, ont intimid\u00e9 les membres de la commission pour qu\u2019ils publient rapidement un rapport approuvant la version de l\u2019assassinat selon laquelle il s\u2019agissait d\u2019un tireur isol\u00e9 et fou. Le leader de la minorit\u00e9 de la Chambre des repr\u00e9sentants, Gerald Ford, membre de la commission, a r\u00e9vis\u00e9 le rapport final du personnel pour modifier l\u2019endroit o\u00f9 la balle a p\u00e9n\u00e9tr\u00e9 dans le corps de Kennedy, sauvant ainsi la th\u00e9orie de la \u00ab\u00a0balle magique\u00a0\u00bb de Hoover. Apr\u00e8s que les conclusions de la Commission Warren ont \u00e9t\u00e9 ridiculis\u00e9es comme \u00e9tant un blanchiment, Johnson a ordonn\u00e9 au FBI de mettre sur \u00e9coute les critiques du rapport. Pour prot\u00e9ger l\u2019histoire officielle, la commission a scell\u00e9 les dossiers cl\u00e9s pendant 75 ans. La v\u00e9rit\u00e9 n\u2019\u00e9claterait qu\u2019une fois que toutes les personnes impliqu\u00e9es dans la dissimulation auraient obtenu leur pension et seraient mortes.<\/p>\n<p>La controverse entourant la Commission Warren a incit\u00e9 la CIA \u00e0 s\u2019attaquer officiellement \u00e0 la notion de th\u00e9orie du complot. Dans une alerte adress\u00e9e en 1967 \u00e0 ses stations et bases \u00e0 l\u2019\u00e9tranger, la CIA d\u00e9clare que le fait que pr\u00e8s de la moiti\u00e9 des Am\u00e9ricains ne croient pas qu\u2019Oswald a agi seul \u00ab\u00a0est un sujet de pr\u00e9occupation pour le gouvernement am\u00e9ricain, y compris pour notre organisation\u00a0\u00bb et met en danger \u00ab\u00a0toute la r\u00e9putation du gouvernement am\u00e9ricain\u00a0\u00bb. Le m\u00e9mo demandait aux destinataires d&#8217;\u00a0\u00bbemployer des moyens de propagande\u00a0\u00bb et d\u2019exploiter \u00ab\u00a0les contacts amis de l\u2019\u00e9lite (en particulier les politiciens et les \u00e9diteurs), en soulignant\u2026 certaines parties du discours sur la conspiration semblent \u00eatre d\u00e9lib\u00e9r\u00e9ment g\u00e9n\u00e9r\u00e9es par des propagandistes communistes.\u00a0\u00bb La preuve ultime de l\u2019innocence du gouvernement : \u00ab\u00a0Une conspiration \u00e0 l\u2019\u00e9chelle souvent sugg\u00e9r\u00e9e serait impossible \u00e0 dissimuler aux \u00c9tats-Unis.\u00a0\u00bb<\/p>\n<p>La CIA a toutefois dissimul\u00e9 un large \u00e9ventail d\u2019assassinats et de coups d\u2019\u00c9tat \u00e9trangers qu\u2019elle a men\u00e9s jusqu\u2019\u00e0 ce que des enqu\u00eates du Congr\u00e8s, au milieu des ann\u00e9es 1970, ne l\u00e8vent le voile. Le New York Times, <a href=\"https:\/\/www.nytimes.com\/1977\/12\/26\/archives\/cable-sought-to-discredit-critics-of-warren-report.html\" target=\"_blank\" rel=\"noopener\">qui a r\u00e9v\u00e9l\u00e9 le m\u00e9mo de la CIA en 1977<\/a>, a not\u00e9 que la CIA \u00ab\u00a0a r\u00e9uni sa machine de propagande pour soutenir une question qui pr\u00e9occupe beaucoup plus les Am\u00e9ricains, et la CIA elle-m\u00eame, que les citoyens d\u2019autres pays\u00a0\u00bb. Selon l\u2019historien Lance deHaven-Smith, <a href=\"https:\/\/books.google.com\/books?id=Pkp2MvLAvAUC&amp;pg=PA25&amp;lpg=PA25&amp;dq=campaign+to+popularize+the+term+%E2%80%98conspiracy+theory%E2%80%99+and+make+conspiracy+belief+a+target+of+ridicule+and+hostility+must+be+credited&amp;source=bl&amp;ots=h_OxqrBUOU&amp;sig=ACfU3U1PgT9AoW8c_QCDV6hVEC5BbteFTA&amp;hl=en&amp;sa=X&amp;ved=2ahUKEwj4iaKZ16zxAhUhKFkFHWyJBfEQ6AEwAXoECAIQAw#v=onepage&amp;q=campaign%20to%20popularize%20the%20term%20%E2%80%98conspiracy%20theory%E2%80%99%20and%20make%20conspiracy%20belief%20a%20target%20of%20ridicule%20and%20hostility%20must%20be%20credited&amp;f=false\" target=\"_blank\" rel=\"noopener\">auteur de <em>Conspiracy Theory in America<\/em><\/a>, \u00ab\u00a0la campagne de la CIA visant \u00e0 populariser le terme \u00ab\u00a0th\u00e9orie du complot\u00a0\u00bb et \u00e0 faire de la croyance au complot une cible de ridicule et d\u2019hostilit\u00e9 doit \u00eatre cr\u00e9dit\u00e9e\u2026 d\u2019\u00eatre l\u2019une des initiatives de propagande les plus r\u00e9ussies de tous les temps.\u00a0\u00bb (En 2014, la CIA a publi\u00e9 <a href=\"https:\/\/nsarchive2.gwu.edu\/NSAEBB\/NSAEBB493\/docs\/intell_ebb_026.PDF\" target=\"_blank\" rel=\"noopener\">un rapport fortement expurg\u00e9<\/a> <a href=\"https:\/\/www.politico.com\/magazine\/story\/2015\/10\/jfk-assassination-john-mccone-warren-commission-cia-213197\/\" target=\"_blank\" rel=\"noopener\">admettant<\/a> qu\u2019elle avait \u00e9t\u00e9 \u00ab\u00a0complice\u00a0\u00bb d\u2019une \u00ab\u00a0dissimulation\u00a0\u00bb de JFK en retenant des informations \u00ab\u00a0incendiaires\u00a0\u00bb \u00e0 la Commission Warren).<\/p>\n<p>L\u2019administration Johnson a \u00e9galement cherch\u00e9 \u00e0 d\u00e9peindre les critiques de sa politique de guerre au Vietnam comme des fous du complot, du moins quand elle ne les d\u00e9peignait pas comme des laquais communistes. Au cours des audiences du S\u00e9nat de 1968 sur l\u2019incident du golfe du Tonkin, le secr\u00e9taire \u00e0 la D\u00e9fense Robert McNamara a d\u00e9nonc\u00e9 les \u00ab\u00a0insinuations monstrueuses\u00a0\u00bb selon lesquelles les \u00c9tats-Unis avaient cherch\u00e9 \u00e0 provoquer une attaque nord-vietnamienne et <a href=\"https:\/\/books.google.com\/books?id=XxE3AQAAIAAJ&amp;pg=PA19&amp;lpg=PA19&amp;dq=MCNAMARA+%22inconceivable+that+anyone+even+remotely+familiar+with+our+society+and+system+of+government+could+suspect+the+existence+of+a+conspiracy%22&amp;source=bl&amp;ots=ToyNeKLH5W&amp;sig=ACfU3U3YE-CWreTBrIqvw1MVu3_FfmU95A&amp;hl=en&amp;sa=X&amp;ved=2ahUKEwiWxYSit6vxAhUJWs0KHaOlA3AQ6AEwAnoECAIQAw#v=onepage&amp;q=MCNAMARA%20%22inconceivable%20that%20anyone%20even%20remotely%20familiar%20with%20our%20society%20and%20system%20of%20government%20could%20suspect%20the%20existence%20of%20a%20conspiracy%22&amp;f=false\" target=\"_blank\" rel=\"noopener\">a d\u00e9clar\u00e9<\/a> qu\u2019il \u00e9tait \u00ab\u00a0inconcevable que quiconque connaissant un tant soit peu notre soci\u00e9t\u00e9 et notre syst\u00e8me de gouvernement puisse soup\u00e7onner l\u2019existence d\u2019une conspiration\u00a0\u00bb visant \u00e0 conduire la nation \u00e0 la guerre sous de faux pr\u00e9textes. Trois ans plus tard, la divulgation des Pentagon Papers a d\u00e9moli la cr\u00e9dibilit\u00e9 de McNamara et d\u2019autres hauts fonctionnaires de l\u2019administration Johnson qui avaient effectivement entra\u00een\u00e9 l\u2019Am\u00e9rique dans la guerre du Vi\u00eat Nam sous de faux pr\u00e9textes.<\/p>\n<div class=\"code-block code-block-5\"><\/div>\n<p><strong>Les condamnations des th\u00e9ories du complot sont devenues une marque de fabrique de l\u2019administration Clinton<\/strong>. En 1995, le pr\u00e9sident Bill Clinton a affirm\u00e9 que les personnes qui pensaient que le gouvernement mena\u00e7ait leur droit constitutionnel \u00e9taient des ingrats d\u00e9rang\u00e9s : \u00ab\u00a0Si vous dites que le gouvernement est en train de conspirer pour vous priver de votre libert\u00e9, vous vous trompez tout simplement\u2026.. Comment osez-vous vous pr\u00e9tendre patriotes et h\u00e9ros !\u00a0\u00bb La m\u00eame ann\u00e9e, la Maison Blanche a compil\u00e9 un rapport enfi\u00e9vr\u00e9 de 331 pages intitul\u00e9 <a href=\"https:\/\/www.washingtonpost.com\/wp-srv\/politics\/special\/pjones\/stories\/pj011097.htm\" target=\"_blank\" rel=\"noopener\">\u00ab\u00a0Communication Stream of Conspiracy Commerce\u00a0\u00bb<\/a>, attaquant les magazines, les groupes de r\u00e9flexion et autres qui avaient critiqu\u00e9 le pr\u00e9sident Clinton. Dans les ann\u00e9es qui ont suivi, de nombreuses organisations condamn\u00e9es dans le rapport de la Maison Blanche ont \u00e9t\u00e9 la cible d\u2019audits de l\u2019IRS, notamment la Heritage Foundation et le magazine American Spectator, ainsi que pr\u00e8s d\u2019une douzaine d\u2019accusateurs individuels tr\u00e8s m\u00e9diatis\u00e9s de Clinton, dont Paula Jones et Gennifer Flowers. Malgr\u00e9 les protestations de Clinton selon lesquelles il ne repr\u00e9sentait aucune menace pour la libert\u00e9, m\u00eame l\u2019ACLU a admis en 1998 que l\u2019administration Clinton s\u2019\u00e9tait \u00ab\u00a0engag\u00e9e dans la surveillance subreptice, comme les \u00e9coutes t\u00e9l\u00e9phoniques, \u00e0 une \u00e9chelle bien plus grande que jamais auparavant\u2026 L\u2019administration utilise des tactiques de peur pour acqu\u00e9rir de vastes nouveaux pouvoirs pour espionner tous les Am\u00e9ricains.\u00a0\u00bb<\/p>\n<p><strong>Certaines all\u00e9gations relatives \u00e0 la \u00ab\u00a0th\u00e9orie du complot\u00a0\u00bb exposent de mani\u00e8re comique la na\u00efvet\u00e9 des responsables officiels de la surveillance.<\/strong> En avril 2016, l\u2019universit\u00e9 Chapman a men\u00e9 une enqu\u00eate aupr\u00e8s des Am\u00e9ricains et a annonc\u00e9 que \u00ab\u00a0la th\u00e9orie du complot la plus r\u00e9pandue aux \u00c9tats-Unis est que le gouvernement dissimule des informations sur les attentats du 11 septembre, un peu plus de la moiti\u00e9 des Am\u00e9ricains ayant cette conviction.\u00a0\u00bb Ce sondage ne demandait pas si les gens croyaient que les World Trade Centers avaient \u00e9t\u00e9 d\u00e9truits par un travail de l\u2019int\u00e9rieur ou que le pr\u00e9sident George W. Bush avait secr\u00e8tement organis\u00e9 les attaques. Au lieu de cela, on a simplement demand\u00e9 aux gens si \u00ab\u00a0le gouvernement dissimule des informations\u00a0\u00bb sur les attaques. Seul un idiot du village, un professeur d\u2019universit\u00e9 ou un \u00e9ditorialiste pourrait supposer que le gouvernement a fait toute la lumi\u00e8re. Trois mois apr\u00e8s la r\u00e9alisation de l\u2019enqu\u00eate de l\u2019universit\u00e9 Chapman, l\u2019administration Obama a finalement publi\u00e9 28 pages d\u2019un rapport du Congr\u00e8s de 2003 qui r\u00e9v\u00e9lait que des responsables du gouvernement saoudien avaient directement financ\u00e9 certains des pirates de l\u2019air du 11 septembre en Am\u00e9rique. Cette r\u00e9v\u00e9lation a fait voler en \u00e9clats le sc\u00e9nario soigneusement construit par l\u2019administration Bush, la Commission du 11 septembre et les l\u00e9gions de m\u00e9dias complices. (Les poursuites se poursuivent devant les tribunaux f\u00e9d\u00e9raux pour obliger le gouvernement am\u00e9ricain \u00e0 divulguer davantage d\u2019informations <a href=\"https:\/\/www.reuters.com\/article\/usa-sept-11-saudi-idINKBN26305P\" target=\"_blank\" rel=\"noopener\">sur le r\u00f4le du gouvernement saoudien<\/a> dans les attentats).<\/p>\n<p><strong>\u00ab\u00a0La th\u00e9orie du complot\u00a0\u00bb est souvent un drapeau de complaisance pour les m\u00e9dias.<\/strong> En 2018, le New York Times a affirm\u00e9 que l\u2019utilisation par Trump de l\u2019expression \u00ab\u00a0Deep State\u00a0\u00bb (Etat Profond, ndlr) et d\u2019une rh\u00e9torique similaire \u00ab\u00a0attisait les craintes qu\u2019il \u00e9rode la confiance du public dans les institutions, sapant l\u2019id\u00e9e de v\u00e9rit\u00e9 objective et semant des soup\u00e7ons g\u00e9n\u00e9ralis\u00e9s sur le gouvernement et les m\u00e9dias d\u2019information.\u00a0\u00bb Cependant, apr\u00e8s que les all\u00e9gations de responsables gouvernementaux anonymes ont suscit\u00e9 la premi\u00e8re destitution de Trump en 2019, le chroniqueur du New York Times James Stewart s\u2019est r\u00e9joui : \u00ab\u00a0Il y a un \u00c9tat profond, il y a une bureaucratie dans notre pays qui s\u2019est engag\u00e9e \u00e0 respecter la Constitution, \u00e0 respecter l\u2019\u00c9tat de droit\u2026 Ils travaillent pour le peuple am\u00e9ricain.\u00a0\u00bb L\u2019\u00e9ditorialiste du New York Times Michelle Cottle a proclam\u00e9 : \u00ab\u00a0L\u2019\u00c9tat profond est bien vivant\u00a0\u00bb et l\u2019a salu\u00e9 comme \u00ab\u00a0une collection de fonctionnaires patriotes.\u00a0\u00bb Presque imm\u00e9diatement apr\u00e8s que son existence n\u2019a plus \u00e9t\u00e9 ni\u00e9e, l\u2019\u00c9tat profond est devenu l\u2019incarnation de la vertu \u00e0 Washington.<\/p>\n<p><strong>L\u2019\u00e9lite m\u00e9diatique peut fabriquer des d\u00e9signations de \u00ab\u00a0th\u00e9orie du complot\u00a0\u00bb presque en un clin d\u2019\u0153il.<\/strong> Une semaine apr\u00e8s le jour des \u00e9lections de 2020, le New York Times a publi\u00e9 un gros titre en haut de la premi\u00e8re page : \u00ab\u00a0Les officiels des \u00e9lections dans tout le pays n\u2019ont trouv\u00e9 aucune fraude.\u00a0\u00bb Comment le Times l\u2019a-t-il su ? Ses journalistes ont appel\u00e9 chaque \u00c9tat et ont demand\u00e9 : \u00ab\u00a0Avez-vous constat\u00e9 des fraudes ?\u00a0\u00bb. Les fonctionnaires \u00e9lectoraux ont r\u00e9pondu \u00ab\u00a0non\u00a0\u00bb, prouvant ainsi que quiconque remettait en question la victoire de Biden faisait la promotion d\u2019une conspiration sans fondement. Alors que les principaux politiciens lib\u00e9raux ont d\u00e9nonc\u00e9 les soci\u00e9t\u00e9s de vote \u00e9lectronique comme n\u2019ayant aucun compte \u00e0 rendre et \u00e9tant malhonn\u00eates en 2019, tous les doutes concernant ces soci\u00e9t\u00e9s sont devenus des \u00ab\u00a0conspirations\u00a0\u00bb apr\u00e8s ce titre du Times. Le Times a contribu\u00e9 \u00e0 stimuler une cacophonie m\u00e9diatique noyant toute personne se plaignant de la r\u00e9colte des bulletins de vote, de l\u2019envoi massif ill\u00e9gal de bulletins de vote par correspondance ou des \u00e9checs g\u00e9n\u00e9ralis\u00e9s de v\u00e9rification de l\u2019identification des \u00e9lecteurs.<\/p>\n<p><strong>En fait, les accusations de \u00ab\u00a0th\u00e9orie du complot\u00a0\u00bb ont aid\u00e9 Biden \u00e0 remporter l\u2019\u00e9lection pr\u00e9sidentielle de 2020.<\/strong> Comme l\u2019a r\u00e9cemment fait remarquer le s\u00e9nateur Lindsey Graham (R-SC), si les Am\u00e9ricains croyaient que le virus COVID-19 avait \u00e9t\u00e9 cr\u00e9\u00e9 dans un laboratoire du gouvernement chinois, Trump aurait probablement remport\u00e9 l\u2019\u00e9lection, car les \u00e9lecteurs auraient cherch\u00e9 un dirigeant capable de se montrer ferme envers la Chine. Mais l\u2019explication de l\u2019origine du laboratoire a rapidement \u00e9t\u00e9 qualifi\u00e9e d\u2019h\u00e9r\u00e9sie pro-Trump. Le Washington Post a d\u00e9nonc\u00e9 le s\u00e9nateur Tom Cotton (R-AR,) pour avoir sugg\u00e9r\u00e9 que le virus provenait du laboratoire, ce qui \u00e9tait soi-disant une \u00ab\u00a0th\u00e9orie du complot d\u00e9j\u00e0 d\u00e9mystifi\u00e9e.\u00a0\u00bb Vingt-sept \u00e9minents scientifiques <a href=\"https:\/\/www.sciencemag.org\/news\/2020\/02\/scientists-strongly-condemn-rumors-and-conspiracy-theories-about-origin-coronavirus\" target=\"_blank\" rel=\"noopener\">ont sign\u00e9 une lettre<\/a> dans le Lancet : \u00ab\u00a0Nous nous unissons pour condamner fermement les th\u00e9ories du complot sugg\u00e9rant que le COVID-19 n\u2019a pas une origine naturelle\u2026 Les th\u00e9ories du complot ne font rien d\u2019autre que de susciter la peur, les rumeurs et les pr\u00e9jug\u00e9s qui mettent en p\u00e9ril notre collaboration mondiale dans la lutte contre ce virus.\u00a0\u00bb The Lancet n\u2019a r\u00e9v\u00e9l\u00e9 que la semaine derni\u00e8re que <a href=\"https:\/\/nypost.com\/2021\/06\/22\/media-allowed-itself-to-be-duped-by-one-man-on-covid-19\/\" target=\"_blank\" rel=\"noopener\">l\u2019un des signataires<\/a> et la personne <a href=\"https:\/\/nypost.com\/2021\/06\/22\/ecohealth-alliance-head-daszak-leaves-un-backed-covid-origins-probe\/\" target=\"_blank\" rel=\"noopener\">qui a organis\u00e9 la campagne de signature de la lettre<\/a> dirigeaient une organisation qui recevait des subventions du gouvernement am\u00e9ricain pour ses travaux au laboratoire de l\u2019Institut de virologie de Wuhan. Le pr\u00e9sident Biden a ordonn\u00e9 aux agences de renseignement am\u00e9ricaines de r\u00e9examiner la situation pour tenter de d\u00e9terminer l\u2019origine du COVID-19.<\/p>\n<p><strong>Les accusations de \u00ab\u00a0th\u00e9oriciens du complot\u00a0\u00bb vont-elles permettre au FBI et \u00e0 d\u2019autres agences f\u00e9d\u00e9rales de sortir de prison en ce qui concerne l\u2019affrontement du 6 janvier au Capitole ?<\/strong> Apr\u00e8s que Tucker Carlson, de Fox News, a pr\u00e9sent\u00e9 des all\u00e9gations selon lesquelles des informateurs ou des agents du FBI auraient \u00e9t\u00e9 \u00e0 l\u2019origine de l\u2019\u00e9meute, le Washington Post a rapidement d\u00e9nonc\u00e9 sa \u00ab\u00a0th\u00e9orie sauvage et sans fondement\u00a0\u00bb, tandis que le Huffington Post a d\u00e9nonc\u00e9 sa \u00ab\u00a0ridicule th\u00e9orie du complot\u00a0\u00bb. Peu importe combien de fois le FBI a \u00e9t\u00e9 l\u2019instigateur de complots terroristes ou de violences politiques au cours des 60 derni\u00e8res ann\u00e9es (y compris le complot visant \u00e0 kidnapper la gouverneure du Michigan, Gretchen Whitmer, en novembre dernier). Au lieu de cela, les gens d\u00e9cents ne doivent rien faire pour mettre en p\u00e9ril le r\u00e9cit officiel du 6 janvier comme un horrible \u00e9v\u00e9nement terroriste priv\u00e9 au m\u00eame titre que la guerre de 1812, Pearl Harbor et les attentats du 11 septembre.<\/p>\n<p><strong>La \u00ab\u00a0th\u00e9orie du complot\u00a0\u00bb est une phrase magique qui efface tous les abus f\u00e9d\u00e9raux ant\u00e9rieurs<\/strong>. De nombreux lib\u00e9raux qui invoquent cette phrase citent aussi rituellement un livre de 1965 de l\u2019ancien communiste Richard Hofstadter, The Paranoid Style in American Politics. Hofstadter d\u00e9crivait la m\u00e9fiance \u00e0 l\u2019\u00e9gard du gouvernement comme une procuration de la maladie mentale, un paradigme qui rend le caract\u00e8re des critiques plus important que la conduite des agences gouvernementales. Pour Hofstadter, c\u2019\u00e9tait une v\u00e9rit\u00e9 \u00e9vidente que le gouvernement \u00e9tait digne de confiance parce que la politique am\u00e9ricaine avait \u00ab\u00a0une sorte de code professionnel\u2026 incarnant la sagesse pratique de g\u00e9n\u00e9rations de politiciens\u00a0\u00bb.<\/p>\n<p><strong>Une grande partie de la rage de l\u2019establishment contre les \u00ab\u00a0th\u00e9ories du complot\u00a0\u00bb a \u00e9t\u00e9 motiv\u00e9e par la notion selon laquelle les dirigeants ont droit \u00e0 une ob\u00e9issance intellectuelle passive. Le m\u00eame \u00e9tat d\u2019esprit de l\u00e8se-majest\u00e9 a \u00e9t\u00e9 largement adopt\u00e9 pour brouiller l\u2019histoire am\u00e9ricaine.<\/strong> Arthur Schlesinger Jr, l\u2019historien de la cour du pr\u00e9sident John F. Kennedy et un intellectuel lib\u00e9ral v\u00e9n\u00e9r\u00e9, a d\u00e9clar\u00e9 en 2004 dans un article de Playboy : \u00ab\u00a0Les historiens d\u2019aujourd\u2019hui concluent que les colons ont \u00e9t\u00e9 pouss\u00e9s \u00e0 la r\u00e9volte en 1776 en raison de la fausse conviction qu\u2019ils \u00e9taient confront\u00e9s \u00e0 une conspiration britannique visant \u00e0 d\u00e9truire leur libert\u00e9\u00a0\u00bb. L\u2019imposition par les Britanniques de la loi martiale, la confiscation des armes \u00e0 feu, les blocus militaires, la suspension de l\u2019habeas corpus et la censure \u00e9taient-ils simplement une fantaisie d\u00e9r\u00e9gl\u00e9e de Thomas Jefferson ? L\u2019id\u00e9e que les Britanniques ne conspireraient jamais pour d\u00e9truire la libert\u00e9 n\u2019est pas tr\u00e8s populaire \u00e0 Dublin. Pourquoi ferait-on confiance \u00e0 des universitaires qui \u00e9taient aveugles aux menaces britanniques dans les ann\u00e9es 1770 pour juger avec pr\u00e9cision des dangers contemporains pour la libert\u00e9 ?<\/p>\n<p>Comment <a href=\"https:\/\/www.theamericanconservative.com\/articles\/bidens-buffoonish-war-on-extremism\/\" target=\"_blank\" rel=\"noopener\">l\u2019administration Biden<\/a> entend-elle lutter contre les \u00ab\u00a0th\u00e9ories du complot\u00a0\u00bb ? Le rapport Biden sur le terrorisme pr\u00e9conise de \u00ab\u00a0renforcer la confiance dans le gouvernement\u00a0\u00bb en \u00ab\u00a0acc\u00e9l\u00e9rant le travail pour faire face \u00e0 un environnement d\u2019information qui met au d\u00e9fi un discours d\u00e9mocratique sain\u00a0\u00bb. L\u2019\u00e9quipe de Biden s\u2019appuiera-t-elle sur la \u00ab\u00a0solution\u00a0\u00bb sugg\u00e9r\u00e9e par Cass Sunstein : <strong>\u00ab\u00a0l\u2019infiltration cognitive des groupes extr\u00e9mistes\u00a0\u00bb<\/strong> par des agents et des informateurs du gouvernement pour les \u00ab\u00a0miner\u00a0\u00bb de l\u2019int\u00e9rieur ? Un rapport du S\u00e9nat de 1976 sur le programme COINTELPRO du FBI <a href=\"https:\/\/fee.org\/articles\/federal-surveillance-the-threat-to-americans-security\/\" target=\"_blank\" rel=\"noopener\">exigeait des garanties<\/a> qu\u2019une agence f\u00e9d\u00e9rale ne serait plus jamais \u00ab\u00a0autoris\u00e9e \u00e0 mener une guerre secr\u00e8te contre les citoyens qu\u2019elle consid\u00e8re comme des menaces pour l\u2019ordre \u00e9tabli\u00a0\u00bb. En r\u00e9alit\u00e9, le FBI et d\u2019autres agences ont continu\u00e9 \u00e0 mener une guerre secr\u00e8te contre les \u00ab\u00a0menaces\u00a0\u00bb et des l\u00e9gions d\u2019informateurs sont probablement occup\u00e9s \u00e0 \u00ab\u00a0infiltrer cognitivement\u00a0\u00bb en ce moment m\u00eame.<\/p>\n<p><strong>La \u00ab\u00a0th\u00e9orie du complot\u00a0\u00bb restera un des ricanements favoris de l\u2019\u00e9lite politico-m\u00e9diatique. Rien ne peut remplacer le fait que les Am\u00e9ricains d\u00e9veloppent de meilleurs radars de B.S. pour les affirmations gouvernementales et les balivernes priv\u00e9es<\/strong>. En attendant, il y a toujours le rem\u00e8de qu\u2019un article du <a href=\"https:\/\/www.washingtonpost.com\/lifestyle\/wellness\/why-uncertain-times-make-us-susceptible-to-conspiracy-theories--and-how-to-protect-yourself\/2020\/10\/16\/21becf08-0f1a-11eb-8a35-237ef1eb2ef7_story.html\" target=\"_blank\" rel=\"noopener\">Washington Post<\/a> sur la sant\u00e9 a vant\u00e9 \u00e0 la fin de l\u2019ann\u00e9e derni\u00e8re : \u00ab\u00a0Essayez l\u2019imagerie guid\u00e9e. La visualisation de r\u00e9sultats positifs peut aider \u00e0 ma\u00eetriser les \u00e9motions intenses qui pourraient vous rendre plus vuln\u00e9rable aux th\u00e9ories du complot nuisibles.\u00a0\u00bb<\/p>\n<p><strong>Traduction de <a href=\"https:\/\/jimbovard.com\/blog\/2021\/06\/24\/the-conspiracy-theory-charade\/\" target=\"_blank\" rel=\"noopener\">Jim Bovard<\/a> par <a href=\"https:\/\/www.aubedigitale.com\/\" target=\"_blank\" rel=\"noopener\">Aube Digitale<\/a><\/strong><\/p>\n<p>xxxxx<\/p>\n<div class=\"ob-section ob-section-html\">\n<h3><a href=\"http:\/\/canempechepasnicolas.over-blog.com\/2021\/01\/le-nouveau-croque-mitaine.html\">\u00ab <strong>Extr\u00e9mistes <\/strong>\u00bb : L\u2019\u00e9pouvantail des dirigeants<\/a><\/h3>\n<p>pour justifier leur propre pouvoir<\/p>\n<\/div>\n<div class=\"ob-section ob-section-html\">\n<p><img decoding=\"async\" src=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/1-36.jpg\" \/><\/p>\n<p><strong>D\u00e9tail de \u00ab\u00a0Que viene el coco\u00a0\u00bb de Francisco de Goya, ou \u00ab\u00a0Voici le croque-mitaine\u00a0\u00bb, 1799. (Galerie nationale d\u2019art. Wikimedia Commons)<\/strong><\/p>\n<\/div>\n<div class=\"ob-section ob-section-images ob-default\">\n<div class=\"ob-row-1-col\"><a class=\"ob-link-img\" href=\"https:\/\/image.over-blog.com\/wjSI4o8d_jcQXelvF3IY3WwK2nQ=\/filters:no_upscale()\/image%2F1445552%2F20210118%2Fob_1c9b76_les-crises.png\" rel=\"fancybox\"><img decoding=\"async\" class=\"ob-cell ob-img ob-media\" src=\"https:\/\/image.over-blog.com\/wjSI4o8d_jcQXelvF3IY3WwK2nQ=\/filters:no_upscale()\/image%2F1445552%2F20210118%2Fob_1c9b76_les-crises.png\" alt=\"Le nouveau croque-mitaine\" \/><\/a><\/div>\n<\/div>\n<div class=\"ob-section ob-section-html\">\n<p>\u00ab Extr\u00e9mistes \u00bb, voil\u00e0 un des fameux \u00e9pouvantails dont les politiciens am\u00e9ricains se servent pour justifier leur propre pouvoir. Mais la d\u00e9finition de l\u2019extr\u00e9misme est en mutation permanente. Le seul \u00e9l\u00e9ment constant dans les d\u00e9finitions de l\u2019extr\u00e9misme, c\u2019est que les politiciens gagnent toujours.<\/p>\n<p>Dans les ann\u00e9es 1770, les personnes qui sugg\u00e9raient que le roi d\u2019Angleterre n\u2019avait pas le droit de diriger l\u2019Am\u00e9rique \u00e9taient consid\u00e9r\u00e9es comme des extr\u00e9mistes. En 2013, on trouvait encore dans un document d\u2019instruction du Pentagone que \u00ab les colons qui cherchaient \u00e0 se lib\u00e9rer de la domination britannique \u00bb \u00e9taient un exemple de \u00ab mouvement extr\u00e9miste \u00bb.<\/p>\n<p>Dans les ann\u00e9es 1850, les Sudistes qui proposaient de lib\u00e9rer les esclaves \u00e9taient consid\u00e9r\u00e9s comme de dangereux extr\u00e9mistes souvent r\u00e9duits au silence par la censure. Les Nordistes qui estimaient que le Sud devait \u00eatre militairement d\u00e9truit \u00e9taient consid\u00e9r\u00e9s comme des extr\u00e9mistes, du moins jusqu\u2019\u00e0 ce que John Brown soit v\u00e9n\u00e9r\u00e9.<\/p>\n<p>Dans les ann\u00e9es 1920, les personnes qui sugg\u00e9raient que le pr\u00e9sident devrait avoir le pouvoir de confisquer l\u2019or des citoyens \u00e9taient consid\u00e9r\u00e9es comme des extr\u00e9mistes \u2013 voire des communistes.<\/p>\n<p>Apr\u00e8s 1934, les personnes qui d\u00e9non\u00e7aient la confiscation f\u00e9d\u00e9rale de l\u2019or am\u00e9ricain \u00e9taient souvent consid\u00e9r\u00e9es comme des extr\u00e9mistes.<\/p>\n<p>Apr\u00e8s la Seconde Guerre mondiale, les pr\u00e9sidents invoquaient r\u00e9guli\u00e8rement la lutte contre l\u2019extr\u00e9misme pour justifier leurs assassinats ou salir leurs d\u00e9tracteurs.<\/p>\n<p>En 1952, lorsque les r\u00e9publicains ont critiqu\u00e9 la guerre de Cor\u00e9e comme \u00e9tant inutile, le pr\u00e9sident Harry Truman a condamn\u00e9 \u00ab les extr\u00e9mistes r\u00e9publicains imprudents et irresponsables \u00bb et \u00ab la version mensong\u00e8re de l\u2019histoire dont les extr\u00e9mistes du Parti r\u00e9publicain sont les auteurs \u00bb. Mais les mensonges et les atrocit\u00e9s qui ont entach\u00e9 la campagne militaire am\u00e9ricaine en Cor\u00e9e ont \u00e9t\u00e9 largement reconnus au point de d\u00e9truire la pr\u00e9sidence de Truman.<\/p>\n<p>En 1964, Lyndon Johnson d\u00e9clarait : \u00ab Quand on exerce la pr\u00e9sidence, l\u2019extr\u00e9misme est un vice impardonnable, et la mod\u00e9ration dans les affaires de la Nation est la plus grande vertu \u00bb. Les m\u00e9dias ont pr\u00e9sent\u00e9 Johnson comme un choix mod\u00e9r\u00e9 alors m\u00eame qu\u2019il bombardait intensivement le Nord-Vietnam et que, contrairement \u00e0 ce qu\u2019il avait dit aux \u00e9lecteurs, il pr\u00e9parait une escalade militaire majeure du conflit..<\/p>\n<div id=\"attachment_259435\" class=\"wp-caption aligncenter\">\n<p>&nbsp;<\/p>\n<p id=\"caption-attachment-259435\" class=\"wp-caption-text\">Le pr\u00e9sident Lyndon B. Johnson en 1966 remet une d\u00e9coration \u00e0 un soldat pendant sa visite au Vietnam. (Yoichi Okamoto, LBJ Library, Wikimedia Commons)<\/p>\n<p><a href=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/2-18.jpg\"><img decoding=\"async\" class=\"centered size-full wp-image-259435 loading\" src=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/2-18.jpg\" sizes=\"(max-width: 1536px) 100vw, 1536px\" srcset=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/2-18.jpg 1536w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/2-18-300x200.jpg 300w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/2-18-1024x684.jpg 1024w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/2-18-768x513.jpg 768w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/2-18-569x380.jpg 569w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/2-18-149x100.jpg 149w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/2-18-590x394.jpg 590w\" alt=\"\" width=\"600\" aria-describedby=\"caption-attachment-259435\" data-was-processed=\"true\" \/><\/a><\/p>\n<\/div>\n<p>En 1965, apr\u00e8s que Johnson ait envoy\u00e9 des marines am\u00e9ricains en R\u00e9publique dominicaine pour soutenir une junte militaire qui venait de prendre le pouvoir, il a annonc\u00e9 que \u00ab le peuple dominicain\u2026 ne veut pas d\u2019un gouvernement qui soit un gouvernement d\u2019extr\u00e9mistes que ce soit de gauche ou de droite \u00bb. Tant qu\u2019il d\u00e9non\u00e7ait les extr\u00e9mistes et r\u00e9citait de faux messages d\u2019alerte sur les prises de contr\u00f4le communistes, les milliers de Dominicains tu\u00e9s dans les combats qui suivirent devenaient des sacrifices sur l\u2019autel de la mod\u00e9ration.<\/p>\n<p>En 1966, dans un discours prononc\u00e9 au East-West Center \u00e0 Honolulu, Johnson d\u00e9plorait : \u00ab Il subsiste en Asie des voix repr\u00e9sentant l\u2019extr\u00e9misme et des ap\u00f4tres du militantisme \u00bb. L\u2019ann\u00e9e pr\u00e9c\u00e9dente, son d\u00e9partement d\u2019\u00c9tat avait secr\u00e8tement approuv\u00e9 une r\u00e9pression sauvage des personnes soup\u00e7onn\u00e9es de communisme (ou de gens qui vivaient dans l\u2019entourage de communistes pr\u00e9sum\u00e9s) par l\u2019arm\u00e9e indon\u00e9sienne. Un demi-million d\u2019Indon\u00e9siens ont \u00e9t\u00e9 massacr\u00e9s avec l\u2019approbation de Johnson au cours d\u2019un carnage que la CIA a qualifi\u00e9 de \u00ab l\u2019une des pires \u00e9radication de masse du XXe si\u00e8cle \u00bb.<\/p>\n<p><strong>Clinton et Bush<\/strong><\/p>\n<p>Bill Clinton s\u2019est r\u00e9guli\u00e8rement servi de l\u2019extr\u00e9misme pour ternir l\u2019opposition politique. En 1999, il a d\u00e9clar\u00e9 au Conseil des dirigeants d\u00e9mocrates que \u00ab nous continuons d\u2019\u00eatre confront\u00e9s \u00e0 un niveau d\u2019extr\u00e9misme et de partialit\u00e9 [de la part des r\u00e9publicains] qui est particuli\u00e8rement effrayant pour les int\u00e9r\u00eats \u00e0 long terme de l\u2019Am\u00e9rique.\u00bb Mais ce ne sont pas les r\u00e9publicains qui se sont engag\u00e9s dans six ann\u00e9es de mensonges permanents pour \u00e9tendre et sacraliser le pouvoir f\u00e9d\u00e9ral. A la veille des \u00e9lections de 2000, Clinton a d\u00e9clar\u00e9 : \u00ab Il faut bien que quelqu\u2019un fasse ce que j\u2019ai fait ces six derni\u00e8res ann\u00e9es, c\u2019est-\u00e0-dire arr\u00eater l\u2019extr\u00e9misme \u00e0 Washington, et il est clair qu\u2019on a qu\u2019un seul choix : Al Gore.\u00bb Gore a perdu, en partie parce que de nombreux \u00e9lecteurs craignaient qu\u2019il ne renforce l\u2019extr\u00e9misme \u00e0 Washington.<\/p>\n<p>Avant septembre 2001, quiconque sugg\u00e9rait que le gouvernement am\u00e9ricain menait une croisade pour \u00ab d\u00e9barrasser le monde du mal \u00bb aurait \u00e9t\u00e9 qualifi\u00e9 \u00e0 la fois d\u2019extr\u00e9miste et de cingl\u00e9. Mais lorsque c\u2019est exactement ce qu\u2019a promis George W. Bush trois jours apr\u00e8s le 11 septembre, les m\u00e9dias l\u2019ont acclam\u00e9 et sa c\u00f4te de popularit\u00e9 a grimp\u00e9 en fl\u00e8che.<\/p>\n<div id=\"attachment_259436\" class=\"wp-caption aligncenter\">\n<p>&nbsp;<\/p>\n<p id=\"caption-attachment-259436\" class=\"wp-caption-text\">Le 14 septembre 2001, debout sur un camion de pompiers d\u00e9glingu\u00e9 \u00e0 Ground Zero, le pr\u00e9sident George W. Bush, en compagnie de Bob Beckwith, pompier retrait\u00e9 de New York improvise un discours. (Eric Draper, George W. Bush Presidential Library and Museum, U.S. National Archives)<\/p>\n<p><a href=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/3-16.jpg\"><img decoding=\"async\" class=\"centered size-full wp-image-259436 loading\" src=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/3-16.jpg\" sizes=\"(max-width: 1000px) 100vw, 1000px\" srcset=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/3-16.jpg 1000w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/3-16-300x200.jpg 300w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/3-16-768x512.jpg 768w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/3-16-570x380.jpg 570w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/3-16-149x100.jpg 149w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/3-16-590x394.jpg 590w\" alt=\"\" width=\"600\" aria-describedby=\"caption-attachment-259436\" data-was-processed=\"true\" \/><\/a><\/p>\n<\/div>\n<p>En 2004, apr\u00e8s que le gouvernement afghan contr\u00f4l\u00e9 par les \u00c9tats-Unis ait organis\u00e9 des \u00e9lections frauduleuses, Bush a d\u00e9clar\u00e9 : \u00ab Le succ\u00e8s des \u00e9lections en Afghanistan prouve un rejet cat\u00e9gorique du cynisme et de l\u2019extr\u00e9misme et c\u2019est un hommage au triomphe de la libert\u00e9 et de l\u2019espoir \u00bb. Mais l\u2019Afghanistan a rapidement plong\u00e9 dans une spirale infernale de d\u00e9clin, ce qui a incit\u00e9 le gouvernement am\u00e9ricain \u00e0 plus encore truquer les \u00e9lections afghanes suivantes.<\/p>\n<p>En 2004, Bush a sacralis\u00e9 sa guerre contre le terrorisme : \u00ab Cette lutte entre l\u2019extr\u00e9misme politique et les valeurs civilis\u00e9es se manifeste dans de nombreux endroits \u00bb. Et toutes les m\u00e9thodes utilis\u00e9es par l\u2019administration Bush \u2013 y compris la torture \u2013 \u00e9taient par d\u00e9finition \u00ab civilis\u00e9es \u00bb puisque les opposants \u00e9taient des extr\u00e9mistes.<\/p>\n<p>Les extr\u00e9mistes \u00e9taient parmi les hommes de paille pr\u00e9f\u00e9r\u00e9s de Bush. Il a d\u00e9clar\u00e9 \u00e0 un groupe de journalistes : \u00ab Le nom que nous avons donn\u00e9 \u00e0 la guerre contre le terrorisme n\u2019\u00e9tait pas le bon. On devrait dire qu\u2019il s\u2019agit de la lutte contre les extr\u00e9mistes id\u00e9ologiques qui ne croient pas aux soci\u00e9t\u00e9s libres et qui utilisent la terreur comme une arme pour essayer d\u2019\u00e9branler la conscience du monde libre \u00bb. La journaliste du Washington Post Dana Milbank a propos\u00e9 un acronyme pour la nouvelle d\u00e9claration de guerre de Bush : SAIEWDNBIFSWHTUTAAWTTTSTCOTFW. [Struggle Against Ideological Extremists Who Do Not Believe in Free Societies Who Happen to Use Terror as a Weapon to Try to Shake the Conscience of the Free World, LCLEIQNCPASLEQULTCUAPEQELCDML, NdT]<\/p>\n<p>En 2005, dans son discours sur l\u2019\u00e9tat de l\u2019Union au Congr\u00e8s, Bush s\u2019est vant\u00e9 des r\u00e9centes \u00e9lections irakiennes : \u00ab Le monde entier sait maintenant qu\u2019un petit groupe d\u2019extr\u00e9mistes n\u2019ira pas \u00e0 l\u2019encontre de la volont\u00e9 du peuple irakien \u00bb. Les \u00e9lections irakiennes de 2005 ressemblaient en fait plus \u00e0 un r\u00e9f\u00e9rendum style bloc sovi\u00e9tique qu\u2019\u00e0 une r\u00e9union \u00e9lectorale en Nouvelle-Angleterre. Les troupes am\u00e9ricaines se sont rendues sur place, diffusant un message demandant aux \u00e9lecteurs de sortir-et-voter tout en effectuant des raids dans les foyers. Apr\u00e8s que les soldats aient distribu\u00e9 des milliers de sp\u00e9cimens de bulletins de vote, le responsable des \u00e9lections de l\u2019ONU a condamn\u00e9 l\u2019ing\u00e9rence militaire am\u00e9ricaine.<\/p>\n<p><strong>Obama<\/strong><\/p>\n<p>En 2009, dans son premier discours au Congr\u00e8s, Barack Obama a d\u00e9clar\u00e9 : \u00ab Pour vaincre l\u2019extr\u00e9misme, nous devons aussi \u00eatre vigilants dans le maintien des valeurs que d\u00e9fendent nos troupes, car il n\u2019y a pas aucune force au monde qui soit plus puissante que l\u2019exemple de l\u2019Am\u00e9rique \u00bb. Obama s\u2019est servi de l\u2019extr\u00e9misme pour justifier toutes les coups de force qu\u2019il a commis. Dans le cadre de sa guerre contre l\u2019extr\u00e9misme violent, l\u2019administration Obama a revendiqu\u00e9 le droit de tuer des Am\u00e9ricains sans proc\u00e8s, sans pr\u00e9avis et sans que les victimes puissent s\u2019y opposer l\u00e9galement.<\/p>\n<p>Dans un discours prononc\u00e9 en d\u00e9cembre 2009 \u00e0 West Point, Obama a annonc\u00e9 qu\u2019il enverrait beaucoup plus de soldats am\u00e9ricains en Afghanistan dans le cadre de la \u00ab lutte contre l\u2019extr\u00e9misme violent \u00bb, laquelle serait, selon lui, \u00ab un crit\u00e8re p\u00e9renne de notre soci\u00e9t\u00e9 libre \u00bb. Plus d\u2019un millier d\u2019Am\u00e9ricains ont ensuite \u00e9t\u00e9 tu\u00e9s en Afghanistan dans une escalade qui n\u2019a fait que prolonger la guerre. La CIA avait cherch\u00e9 \u00e0 avertir Obama que sa \u00ab surench\u00e8re \u00bb serait un \u00e9chec, mais une petite foule au cimeti\u00e8re d\u2019Arlington \u00e9tait un faible prix \u00e0 payer pour ternir l\u2019image de dur \u00e0 cuire d\u2019Obama.<\/p>\n<div id=\"attachment_259437\" class=\"wp-caption aligncenter\">\n<p id=\"caption-attachment-259437\" class=\"wp-caption-text\">Le pr\u00e9sident Barack Obama rencontre les dirigeants du Congr\u00e8s et les pr\u00e9sidents des commissions pour discuter de l\u2019Afghanistan et du Pakistan, 6 octobre 2009. (Maison Blanche, Pete Souza)<\/p>\n<p><a href=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/4-11.jpg\"><img decoding=\"async\" class=\"centered size-full wp-image-259437 loading\" src=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/4-11.jpg\" sizes=\"(max-width: 1000px) 100vw, 1000px\" srcset=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/4-11.jpg 1000w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/4-11-300x200.jpg 300w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/4-11-768x512.jpg 768w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/4-11-570x380.jpg 570w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/4-11-149x100.jpg 149w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/4-11-590x394.jpg 590w\" alt=\"\" width=\"600\" aria-describedby=\"caption-attachment-259437\" data-was-processed=\"true\" \/><\/a><\/p>\n<\/div>\n<p>En 2011, Obama a l\u00e9gitim\u00e9 le bombardement de la Libye, ce pays ne devait pas devenir \u00ab un nouveau refuge pour les extr\u00e9mistes \u00bb. Apr\u00e8s que les \u00c9tats-Unis ont aid\u00e9 \u00e0 renverser le dictateur libyen, les extr\u00e9mistes ont pris le contr\u00f4le d\u2019une grande partie du pays et la violence a fait des milliers de victimes (dont quatre Am\u00e9ricains tu\u00e9s \u00e0 Benghazi en 2012). Les march\u00e9s aux esclaves qui ont commenc\u00e9 \u00e0 se tenir ouvertement en Libye apr\u00e8s l\u2019attentat am\u00e9ricain ne faisaient pas officiellement partie de la campagne anti-extr\u00e9misme du pr\u00e9sident.<\/p>\n<p>En 2014, Obama a justifi\u00e9 l\u2019intervention militaire am\u00e9ricaine en Syrie : \u00ab Ce que nous combattons aussi, est une pouss\u00e9e d\u2019id\u00e9ologique d\u2019extr\u00e9misme qui a pris racine dans de trop nombreuses parties de la r\u00e9gion \u00bb. L\u2019administration Obama a lanc\u00e9 plus de 5 000 frappes a\u00e9riennes sur des cibles syriennes, mais ses d\u00e9clarations pr\u00e9tendument vertueuses ont \u00e9t\u00e9 le seul aspect coh\u00e9rent de sa politique. Le gouvernement am\u00e9ricain a fourni des armes et de l\u2019argent \u00e0 des groupes radicaux li\u00e9s \u00e0 al-Qa\u00efda et \u00e0 d\u2019autres fanatiques musulmans dans le cadre de la campagne am\u00e9ricaine visant \u00e0 renverser le gouvernement Assad. La politique am\u00e9ricaine \u00e9tait si confuse que des rebelles syriens soutenus par le Pentagone ont ouvertement combattu des rebelles syriens soutenus par la CIA.<\/p>\n<p><strong>Trump<\/strong><\/p>\n<p>En mai 2017, Donald Trump s\u2019est rendu en Arabie Saoudite et a proclam\u00e9 que les \u00c9tats-Unis et les Saoudiens \u00ab cherchent \u00e0 lancer de nouvelles initiatives pour contrer les messages extr\u00e9mistes violents, d\u00e9sorganiser le financement du terrorisme et faire progresser la coop\u00e9ration en mati\u00e8re de d\u00e9fense \u00bb. Le fait que des repr\u00e9sentants du gouvernement saoudien aient fourni une aide financi\u00e8re aux pirates de l\u2019air du 11 septembre (15 des 19 \u00e9taient des Saoudiens) n\u2019a pas suffi \u00e0 g\u00e2cher la session de photos.<\/p>\n<div id=\"attachment_259438\" class=\"wp-caption aligncenter\">\n<p>&nbsp;<\/p>\n<p id=\"caption-attachment-259438\" class=\"wp-caption-text\">Le pr\u00e9sident Donald Trump et la premi\u00e8re dame Melania Trump se joignent au roi Salman bin Abdulaziz Al Saud d\u2019Arabie Saoudite et au pr\u00e9sident \u00e9gyptien Abdel Fattah Al Sisi, le 21 mai 2017, pour l\u2019ouverture du Centre mondial de lutte contre l\u2019id\u00e9ologie extr\u00e9miste. (Maison Blanche, Shealah Craighead)<\/p>\n<p><a href=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/5-9.jpg\"><img decoding=\"async\" class=\"centered size-full wp-image-259438 loading\" src=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/5-9.jpg\" sizes=\"(max-width: 960px) 100vw, 960px\" srcset=\"https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/5-9.jpg 960w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/5-9-300x200.jpg 300w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/5-9-768x512.jpg 768w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/5-9-570x380.jpg 570w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/5-9-149x100.jpg 149w, https:\/\/www.les-crises.fr\/wp-content\/uploads\/2020\/12\/5-9-590x393.jpg 590w\" alt=\"\" width=\"600\" aria-describedby=\"caption-attachment-259438\" data-was-processed=\"true\" \/><\/a><\/p>\n<\/div>\n<p>Trois mois plus tard, la Maison Blanche a publi\u00e9 une synth\u00e8se de l\u2019appel t\u00e9l\u00e9phonique de Trump au roi Salman bin Abdulaziz al-Saud qui souligne que les deux dirigeants \u00ab ont discut\u00e9 de la n\u00e9cessit\u00e9 de vaincre le terrorisme, de tarir le financement du terrorisme et de combattre l\u2019id\u00e9ologie extr\u00e9miste \u00bb. Le fait que les saoudiens ont toujours \u00e9t\u00e9 parmi les plus grands financeurs du terrorisme et des mouvements islamiques radicaux dans le monde n\u2019a en rien perturb\u00e9 le communiqu\u00e9 de presse.<\/p>\n<p>En novembre 2017, apr\u00e8s que des hommes arm\u00e9s aient tu\u00e9 des centaines de personnes dans une mosqu\u00e9e en \u00c9gypte, Trump a proclam\u00e9 : \u00ab Le monde ne tol\u00e9rera pas le terrorisme. Nous devons les vaincre militairement et discr\u00e9diter l\u2019id\u00e9ologie extr\u00e9miste qui est \u00e0 la racine de leur existence ! Deux ans plus tard, il a interloqu\u00e9 les participants \u00e0 un sommet international en saluant le dirigeant \u00e9gyptien Abdel Fattah el-Sisi le qualifiant de \u00ab mon dictateur pr\u00e9f\u00e9r\u00e9 \u00bb. Sisi est connu pour ses assassinats de dissidents, ses arrestations massives et la d\u00e9tention arbitraire de toute personne qui d\u00e9nonce ses exactions. Mais comme Sisi suivait g\u00e9n\u00e9ralement les ordres de Washington, sa qualification de mod\u00e9r\u00e9 \u00e9tait sans appel.<\/p>\n<p><strong>Pavillon de complaisance<\/strong><\/p>\n<p>La d\u00e9finition de ce qu\u2019est \u00ab l\u2019extr\u00e9misme \u00bb est souvent un pavillon de complaisance pour l\u2019establishment. Comme l\u2019a not\u00e9 un manuel de formation du Pentagone concernant le danger des groupes de haine, \u00ab Toutes les nations ont une id\u00e9ologie, quelque chose en quoi elles croient. Lorsqu\u2019une id\u00e9ologie politique se situe en dehors des normes d\u2019une soci\u00e9t\u00e9, elle est qualifi\u00e9e d\u2019extr\u00e9misme \u00bb. En d\u2019autres termes, les croyances qui divergent des opinions dominantes ou approuv\u00e9es sont \u00ab extr\u00e9mistes \u00bb par d\u00e9finition. Et qui peut d\u00e9clarer ce qu\u2019il est acceptable de croire ? Justement ces m\u00eames politiciens et agences gouvernementales dont le pouvoir est renforc\u00e9 par les opinions dominantes.<\/p>\n<p>L\u2019 \u00ab extr\u00e9misme \u00bb est encore plus brumeux que le \u00ab terrorisme \u00bb. Avec le terrorisme, au moins les criminels sont de connivence quand il s\u2019agit d\u2019infliger la violence. Un extr\u00e9miste, en revanche, est quelqu\u2019un qui a une mauvaise attitude et qui pourrait faire quelque chose de d\u00e9plaisant dans le futur. La r\u00e9pression \u00e0 l\u2019encontre des extr\u00e9mistes pr\u00e9sum\u00e9s peut constituer l\u2019outil parfait pour diaboliser l\u2019opposition politique dans le pays et \u00e0 l\u2019\u00e9tranger.<\/p>\n<p>Dans le m\u00eame temps, les politiciens d\u00e9noncent l\u2019extr\u00e9misme et les m\u00e9dias de l\u2019establishment se gardent bien de rendre publics les abus du gouvernement. Plus l\u2019accusation de tendances extr\u00e9mistes est fond\u00e9e, plus il est facile pour les responsables gouvernementaux de couvrir leurs atrocit\u00e9s.<\/p>\n<p>Au d\u00e9but de 2004, avant que les photos d\u2019Abu Ghraib ne soient divulgu\u00e9es, les personnes qui affirmaient que le gouvernement am\u00e9ricain torturait des d\u00e9tenus \u00e9taient consid\u00e9r\u00e9es comme des extr\u00e9mistes. Une d\u00e9cennie plus tard, apr\u00e8s qu\u2019un rapport du S\u00e9nat ait document\u00e9 la mani\u00e8re dont la CIA avait mis en place un r\u00e9gime mondial de torture, les personnes qui \u00e9taient en faveur de vigoureuses poursuites judiciaires visant les tortionnaires de la CIA \u00e9taient consid\u00e9r\u00e9es comme des extr\u00e9mistes. De m\u00eame, les personnes qui, apr\u00e8s le 11 septembre, affirmaient que le gouvernement am\u00e9ricain se rendait coupable de violations ill\u00e9gales et \u00e0 grande \u00e9chelle de la vie priv\u00e9e des Am\u00e9ricains \u00e9taient consid\u00e9r\u00e9es comme des extr\u00e9mistes. Apr\u00e8s qu\u2019Edward Snowden ait divulgu\u00e9 des documents en 2013 prouvant que l\u2019Administration de la s\u00e9curit\u00e9 nationale (NSA) avait ill\u00e9galement saisi les courriels de millions d\u2019Am\u00e9ricains, seuls les extr\u00e9mistes \u00e9taient favorables \u00e0 la poursuite judiciaire des chefs de la NSA qui avaient menti au Congr\u00e8s et au public am\u00e9ricain au sujet de leur surveillance illicite.<\/p>\n<p>Les Am\u00e9ricains ont toujours accept\u00e9 que le gouvernement s\u2019empare d\u2019un pouvoir pratiquement illimit\u00e9 quand il s\u2019agit de guerre contre l\u2019extr\u00e9misme. Mais permettre aux politiciens de d\u00e9finir l\u2019extr\u00e9misme, c\u2019est les laisser vilipender pr\u00e9ventivement ceux qui sont leurs plus farouches critiques. Heureusement, il n\u2019est pas encore devenu ill\u00e9gal de donner \u00e0 penser que le gouvernement lui-m\u00eame est devenu le plus grand des extr\u00e9mistes.<\/p>\n<p><strong>James Bovard est conseiller politique aupr\u00e8s de la fondation The Future of Freedom. Il est chroniqueur pour USA Today et a \u00e9crit pour le New York Times, le Wall Street Journal, le Washington Post, New Republic, le Reader\u2019s Digest, Playboy, American Spectator, Investors Business Daily et de nombreuses autres publications. Il est l\u2019auteur de Freedom Frauds : Hard Lessons in American Liberty (2017, publi\u00e9 par FFF) ; Public Policy Hooligan (2012) ; Attention Deficit Democracy (2006) ; The Bush Betrayal (2004) ; Terrorism and Tyranny (2003) ; Feeling Your Pain (2000) ; Freedom in Chains (1999) ; Shakedown (1995) ; Lost Rights (1994) ; The Fair Trade Fraud (1991) ; et The Farm Fiasco (1989). Lisez son blog. Envoyez-lui un courriel.<\/strong><\/p>\n<p>Source :\u00a0<a href=\"https:\/\/consortiumnews.com\/2020\/12\/11\/extremism-as-a-ticket-to-tyrannize\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consortium News, James Bovard<\/a>, 11-12-2020<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Here are a couple recent articles translated into French. The &#8220;conspiracy theory&#8221; article was first published by the American Conservative and reposted by Zero Hedge.\u00a0 The second article, on Extremism, was first published by the Future of Freedom Foundation and republished by Consortium News. La com\u00e9die de la \u00ab\u00a0th\u00e9orie du complot\u00a0\u00bb par \u00a0 James Bovard [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2908,476,2907],"class_list":["post-16135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-conspiracy-theory","tag-extremism","tag-french"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>French Translations of Conspiracy Theory and Extremism Articles - James Bovard<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"French Translations of Conspiracy Theory and Extremism Articles - James Bovard\" \/>\n<meta property=\"og:description\" content=\"Here are a couple recent articles translated into French. The &#8220;conspiracy theory&#8221; article was first published by the American Conservative and reposted by Zero Hedge.\u00a0 The second article, on Extremism, was first published by the Future of Freedom Foundation and republished by Consortium News. La com\u00e9die de la \u00ab\u00a0th\u00e9orie du complot\u00a0\u00bb par \u00a0 James Bovard [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/\" \/>\n<meta property=\"og:site_name\" content=\"James Bovard\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jim.bovard\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-28T13:04:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-28T19:18:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jimbovard.com\/blog\/wp-content\/uploads\/2021\/06\/conspiracy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"694\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jimbovard\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"24 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/\"},\"author\":{\"name\":\"Jim\",\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/#\\\/schema\\\/person\\\/79550830ad81c14be529a2c37469974f\"},\"headline\":\"French Translations of Conspiracy Theory and Extremism Articles\",\"datePublished\":\"2021-06-28T13:04:43+00:00\",\"dateModified\":\"2021-06-28T19:18:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/\"},\"wordCount\":5795,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/conspiracy.jpg\",\"keywords\":[\"Conspiracy Theory\",\"extremism\",\"French\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/\",\"url\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/\",\"name\":\"French Translations of Conspiracy Theory and Extremism Articles - James Bovard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/conspiracy.jpg\",\"datePublished\":\"2021-06-28T13:04:43+00:00\",\"dateModified\":\"2021-06-28T19:18:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/#\\\/schema\\\/person\\\/79550830ad81c14be529a2c37469974f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/conspiracy.jpg\",\"contentUrl\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/conspiracy.jpg\",\"width\":800,\"height\":694},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/2021\\\/06\\\/28\\\/french-translations-of-conspiracy-theory-and-extremism-articles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"French Translations of Conspiracy Theory and Extremism Articles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/\",\"name\":\"James Bovard\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/#\\\/schema\\\/person\\\/79550830ad81c14be529a2c37469974f\",\"name\":\"Jim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d95466cfd0934e38803c5035629df727ae4ec1f3f96c6883c05b5c52e2044505?s=96&d=mm&r=r\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d95466cfd0934e38803c5035629df727ae4ec1f3f96c6883c05b5c52e2044505?s=96&d=mm&r=r\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d95466cfd0934e38803c5035629df727ae4ec1f3f96c6883c05b5c52e2044505?s=96&d=mm&r=r\",\"caption\":\"Jim\"},\"description\":\"Bovard's homepage is at http:\\\/\\\/www.jimbovard.com He can be contacted at jim@jimbovard.com James Bovard is the author of ten books. The Wall Street Journal called Bovard \\\"the roving inspector general of the modern state\\\" and Washington Post columnist George Will called him a \\\"one-man truth squad.\\\" His 1994 book, Lost Rights: The Destruction of American Liberty, received the Free Press Association\u2019s Mencken Award as Book of the Year. His Terrorism &amp; Tyranny won the Lysander Spooner \\\"Best Book on Liberty in 2003\\\" award. He received the Thomas Szasz Award for Civil Liberties work, awarded by the Center for Independent Thought and the Freedom Fund Award from the Firearms Civil Rights Defense Fund of the National Rifle Association. Bovard\u2019s writings have been publicly denounced by FBI director Louis Freeh, the Secretary of Agriculture, the Secretary of Housing and Urban Development, the Postmaster General, and the chiefs of the U.S. International Trade Commission, the Drug Enforcement Administration, the Equal Employment Opportunity Commission, and the Federal Emergency Management Agency, as well as by many congressmen and other malcontents.\",\"sameAs\":[\"http:\\\/\\\/www.jimbovard.com\",\"https:\\\/\\\/www.facebook.com\\\/jim.bovard\",\"https:\\\/\\\/x.com\\\/jimbovard\"],\"url\":\"https:\\\/\\\/jimbovard.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"French Translations of Conspiracy Theory and Extremism Articles - James Bovard","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/","og_locale":"en_US","og_type":"article","og_title":"French Translations of Conspiracy Theory and Extremism Articles - James Bovard","og_description":"Here are a couple recent articles translated into French. The &#8220;conspiracy theory&#8221; article was first published by the American Conservative and reposted by Zero Hedge.\u00a0 The second article, on Extremism, was first published by the Future of Freedom Foundation and republished by Consortium News. La com\u00e9die de la \u00ab\u00a0th\u00e9orie du complot\u00a0\u00bb par \u00a0 James Bovard [&hellip;]","og_url":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/","og_site_name":"James Bovard","article_author":"https:\/\/www.facebook.com\/jim.bovard","article_published_time":"2021-06-28T13:04:43+00:00","article_modified_time":"2021-06-28T19:18:11+00:00","og_image":[{"width":800,"height":694,"url":"https:\/\/jimbovard.com\/blog\/wp-content\/uploads\/2021\/06\/conspiracy.jpg","type":"image\/jpeg"}],"author":"Jim","twitter_card":"summary_large_image","twitter_creator":"@jimbovard","twitter_misc":{"Written by":"Jim","Est. reading time":"24 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/#article","isPartOf":{"@id":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/"},"author":{"name":"Jim","@id":"https:\/\/jimbovard.com\/blog\/#\/schema\/person\/79550830ad81c14be529a2c37469974f"},"headline":"French Translations of Conspiracy Theory and Extremism Articles","datePublished":"2021-06-28T13:04:43+00:00","dateModified":"2021-06-28T19:18:11+00:00","mainEntityOfPage":{"@id":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/"},"wordCount":5795,"commentCount":0,"image":{"@id":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/#primaryimage"},"thumbnailUrl":"https:\/\/jimbovard.com\/blog\/wp-content\/uploads\/2021\/06\/conspiracy.jpg","keywords":["Conspiracy Theory","extremism","French"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/","url":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/","name":"French Translations of Conspiracy Theory and Extremism Articles - James Bovard","isPartOf":{"@id":"https:\/\/jimbovard.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/#primaryimage"},"image":{"@id":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/#primaryimage"},"thumbnailUrl":"https:\/\/jimbovard.com\/blog\/wp-content\/uploads\/2021\/06\/conspiracy.jpg","datePublished":"2021-06-28T13:04:43+00:00","dateModified":"2021-06-28T19:18:11+00:00","author":{"@id":"https:\/\/jimbovard.com\/blog\/#\/schema\/person\/79550830ad81c14be529a2c37469974f"},"breadcrumb":{"@id":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/#primaryimage","url":"https:\/\/jimbovard.com\/blog\/wp-content\/uploads\/2021\/06\/conspiracy.jpg","contentUrl":"https:\/\/jimbovard.com\/blog\/wp-content\/uploads\/2021\/06\/conspiracy.jpg","width":800,"height":694},{"@type":"BreadcrumbList","@id":"https:\/\/jimbovard.com\/blog\/2021\/06\/28\/french-translations-of-conspiracy-theory-and-extremism-articles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jimbovard.com\/blog\/"},{"@type":"ListItem","position":2,"name":"French Translations of Conspiracy Theory and Extremism Articles"}]},{"@type":"WebSite","@id":"https:\/\/jimbovard.com\/blog\/#website","url":"https:\/\/jimbovard.com\/blog\/","name":"James Bovard","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jimbovard.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/jimbovard.com\/blog\/#\/schema\/person\/79550830ad81c14be529a2c37469974f","name":"Jim","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d95466cfd0934e38803c5035629df727ae4ec1f3f96c6883c05b5c52e2044505?s=96&d=mm&r=r","url":"https:\/\/secure.gravatar.com\/avatar\/d95466cfd0934e38803c5035629df727ae4ec1f3f96c6883c05b5c52e2044505?s=96&d=mm&r=r","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d95466cfd0934e38803c5035629df727ae4ec1f3f96c6883c05b5c52e2044505?s=96&d=mm&r=r","caption":"Jim"},"description":"Bovard's homepage is at http:\/\/www.jimbovard.com He can be contacted at jim@jimbovard.com James Bovard is the author of ten books. The Wall Street Journal called Bovard \"the roving inspector general of the modern state\" and Washington Post columnist George Will called him a \"one-man truth squad.\" His 1994 book, Lost Rights: The Destruction of American Liberty, received the Free Press Association\u2019s Mencken Award as Book of the Year. His Terrorism &amp; Tyranny won the Lysander Spooner \"Best Book on Liberty in 2003\" award. He received the Thomas Szasz Award for Civil Liberties work, awarded by the Center for Independent Thought and the Freedom Fund Award from the Firearms Civil Rights Defense Fund of the National Rifle Association. Bovard\u2019s writings have been publicly denounced by FBI director Louis Freeh, the Secretary of Agriculture, the Secretary of Housing and Urban Development, the Postmaster General, and the chiefs of the U.S. International Trade Commission, the Drug Enforcement Administration, the Equal Employment Opportunity Commission, and the Federal Emergency Management Agency, as well as by many congressmen and other malcontents.","sameAs":["http:\/\/www.jimbovard.com","https:\/\/www.facebook.com\/jim.bovard","https:\/\/x.com\/jimbovard"],"url":"https:\/\/jimbovard.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jimbovard.com\/blog\/wp-json\/wp\/v2\/posts\/16135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jimbovard.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jimbovard.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jimbovard.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jimbovard.com\/blog\/wp-json\/wp\/v2\/comments?post=16135"}],"version-history":[{"count":4,"href":"https:\/\/jimbovard.com\/blog\/wp-json\/wp\/v2\/posts\/16135\/revisions"}],"predecessor-version":[{"id":16140,"href":"https:\/\/jimbovard.com\/blog\/wp-json\/wp\/v2\/posts\/16135\/revisions\/16140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jimbovard.com\/blog\/wp-json\/wp\/v2\/media\/16137"}],"wp:attachment":[{"href":"https:\/\/jimbovard.com\/blog\/wp-json\/wp\/v2\/media?parent=16135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jimbovard.com\/blog\/wp-json\/wp\/v2\/categories?post=16135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jimbovard.com\/blog\/wp-json\/wp\/v2\/tags?post=16135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}